{"id":859,"date":"2015-11-12T11:00:27","date_gmt":"2015-11-12T10:00:27","guid":{"rendered":"https:\/\/www.alimentoslapedriza.com\/?p=859"},"modified":"2023-09-25T09:30:44","modified_gmt":"2023-09-25T07:30:44","slug":"preocupa-el-exceso-de-peso-de-los-menores","status":"publish","type":"post","link":"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/","title":{"rendered":"Preocupa el exceso de peso de los menores"},"content":{"rendered":"<p style=\"text-align: justify\">El estudio Aladino revela que el 44,5% de los ni\u00f1os y ni\u00f1as espa\u00f1oles de entre seis y nueve a\u00f1os tienen exceso de peso con respecto a los patrones de crecimiento de la OMS.\u00a0Esta realidad no es un problema exclusivamente de Espa\u00f1a ni del mundo desarrollado, sino que manifiesta un problema global de salud p\u00fablica que ya afecta tambi\u00e9n a las sociedades en desarrollo. Estas han visto c\u00f3mo su estilo de vida ha cambiado y acomodan en su d\u00eda a d\u00eda elementos que incitan al sedentarismo y a una dieta doblegada ante los alimentos cal\u00f3ricos.<\/p>\n<p style=\"text-align: justify\">Pese a la gran diversidad de alimentos y la facilidad que tenemos de acceder a ellos, parece que seguimos seleccionando productos refinados, entre otros que nos afectan negativamente. \u00a0Los estudios al respecto evidencian que, desde un punto de vista energ\u00e9tico, no es que se consuman muchas m\u00e1s calor\u00edas que antes, sino que se come de forma m\u00e1s desequilibrada. Y eso lo padecen especialmente los m\u00e1s peque\u00f1os. El sobrepeso y la obesidad son dos de los factores de riesgo m\u00e1s importantes en el desarrollo de enfermedades cr\u00f3nicas no transmisibles. Se estima que un ni\u00f1o obeso tiene un 80% de posibilidades de ser obeso tambi\u00e9n de adulto. Si no se invierte esta tendencia actual, los estudios vaticinan en el futuro un importante aumento del gasto de salud p\u00fablica y, lo que es m\u00e1s alarmante, una significativa p\u00e9rdida de calidad de vida de estos ni\u00f1os cuando sean adultos.<\/p>\n<p style=\"text-align: justify\">Hemos de ser conscientes de que la soluci\u00f3n para este problema est\u00e1 en la mano de los padres y en la acci\u00f3n de inculcarle valores positivos de alimentaci\u00f3n al peque\u00f1o. Una alimentaci\u00f3n sana y equilibrada, estructurada a base de legumbres, verduras, carnes y pescados, cosa que no quita que haya alg\u00fan que otro capricho en medio.<\/p>\n<p style=\"text-align: justify\">Todo esto se debe combinar con el fomento de actividades l\u00fadicas fuera de casa para que nuestro reto\u00f1o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El estudio Aladino revela que el 44,5% de los ni\u00f1os y ni\u00f1as espa\u00f1oles de entre seis y nueve a\u00f1os tienen exceso de peso con respecto a los patrones de crecimiento de la OMS.\u00a0Esta realidad no es un problema exclusivamente de Espa\u00f1a ni del mundo desarrollado, sino que manifiesta un problema global de salud p\u00fablica que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2036,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[30,154,46],"tags":[55,56,57,58,59,60],"class_list":["post-859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-ninos","category-salud","tag-exceso-de-peso","tag-infantil","tag-obesidad","tag-obesidad-infantil","tag-oms","tag-peso"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Preocupa el exceso de peso de los menores - Alimentos La Pedriza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preocupa el exceso de peso de los menores - Alimentos La Pedriza\" \/>\n<meta property=\"og:description\" content=\"El estudio Aladino revela que el 44,5% de los ni\u00f1os y ni\u00f1as espa\u00f1oles de entre seis y nueve a\u00f1os tienen exceso de peso con respecto a los patrones de crecimiento de la OMS.\u00a0Esta realidad no es un problema exclusivamente de Espa\u00f1a ni del mundo desarrollado, sino que manifiesta un problema global de salud p\u00fablica que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/\" \/>\n<meta property=\"og:site_name\" content=\"Alimentos La Pedriza\" \/>\n<meta property=\"article:published_time\" content=\"2015-11-12T10:00:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-25T07:30:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alimentoslapedriza.com\/fr\/wp-content\/uploads\/sites\/12\/2015\/11\/obesidad_infantil.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"775\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"iBrenoc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"iBrenoc\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/blog\\\/preocupa-el-exceso-de-peso-de-los-menores\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/blog\\\/preocupa-el-exceso-de-peso-de-los-menores\\\/\"},\"author\":{\"name\":\"iBrenoc\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/#\\\/schema\\\/person\\\/33591e0e18f812251967156e9f483659\"},\"headline\":\"Preocupa el exceso de peso de los menores\",\"datePublished\":\"2015-11-12T10:00:27+00:00\",\"dateModified\":\"2023-09-25T07:30:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/blog\\\/preocupa-el-exceso-de-peso-de-los-menores\\\/\"},\"wordCount\":353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/blog\\\/preocupa-el-exceso-de-peso-de-los-menores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2015\\\/11\\\/obesidad_infantil.jpg\",\"keywords\":[\"exceso de peso\",\"infantil\",\"obesidad\",\"obesidad infantil\",\"OMS\",\"peso\"],\"articleSection\":[\"Blog\",\"Ni\u00f1os\",\"Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/blog\\\/preocupa-el-exceso-de-peso-de-los-menores\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/blog\\\/preocupa-el-exceso-de-peso-de-los-menores\\\/\",\"url\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/blog\\\/preocupa-el-exceso-de-peso-de-los-menores\\\/\",\"name\":\"Preocupa el exceso de peso de los menores - Alimentos La Pedriza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/blog\\\/preocupa-el-exceso-de-peso-de-los-menores\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/blog\\\/preocupa-el-exceso-de-peso-de-los-menores\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2015\\\/11\\\/obesidad_infantil.jpg\",\"datePublished\":\"2015-11-12T10:00:27+00:00\",\"dateModified\":\"2023-09-25T07:30:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/blog\\\/preocupa-el-exceso-de-peso-de-los-menores\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/blog\\\/preocupa-el-exceso-de-peso-de-los-menores\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/blog\\\/preocupa-el-exceso-de-peso-de-los-menores\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2015\\\/11\\\/obesidad_infantil.jpg\",\"contentUrl\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2015\\\/11\\\/obesidad_infantil.jpg\",\"width\":1240,\"height\":775},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/blog\\\/preocupa-el-exceso-de-peso-de-los-menores\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Preocupa el exceso de peso de los menores\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/\",\"name\":\"Alimentos La Pedriza\",\"description\":\"Legumbres La Pedriza | Prenez votre temps\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/#organization\",\"name\":\"Alimentos La Pedriza\",\"url\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2023\\\/08\\\/Logo-casa-vertical-26.png\",\"contentUrl\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/wp-content\\\/uploads\\\/sites\\\/12\\\/2023\\\/08\\\/Logo-casa-vertical-26.png\",\"width\":512,\"height\":398,\"caption\":\"Alimentos La Pedriza\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/#\\\/schema\\\/person\\\/33591e0e18f812251967156e9f483659\",\"name\":\"iBrenoc\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a933354c7a617a984d8fbf8e98e5511c48f16e03dd9bddfdec0ddefe88c3fada?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a933354c7a617a984d8fbf8e98e5511c48f16e03dd9bddfdec0ddefe88c3fada?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a933354c7a617a984d8fbf8e98e5511c48f16e03dd9bddfdec0ddefe88c3fada?s=96&d=mm&r=g\",\"caption\":\"iBrenoc\"},\"sameAs\":[\"https:\\\/\\\/www.alimentoslapedriza.com\"],\"url\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/fr\\\/blog\\\/author\\\/ibrenoc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preocupa el exceso de peso de los menores - Alimentos La Pedriza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/","og_locale":"es_ES","og_type":"article","og_title":"Preocupa el exceso de peso de los menores - Alimentos La Pedriza","og_description":"El estudio Aladino revela que el 44,5% de los ni\u00f1os y ni\u00f1as espa\u00f1oles de entre seis y nueve a\u00f1os tienen exceso de peso con respecto a los patrones de crecimiento de la OMS.\u00a0Esta realidad no es un problema exclusivamente de Espa\u00f1a ni del mundo desarrollado, sino que manifiesta un problema global de salud p\u00fablica que [&hellip;]","og_url":"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/","og_site_name":"Alimentos La Pedriza","article_published_time":"2015-11-12T10:00:27+00:00","article_modified_time":"2023-09-25T07:30:44+00:00","og_image":[{"width":1240,"height":775,"url":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-content\/uploads\/sites\/12\/2015\/11\/obesidad_infantil.jpg","type":"image\/jpeg"}],"author":"iBrenoc","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"iBrenoc","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/#article","isPartOf":{"@id":"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/"},"author":{"name":"iBrenoc","@id":"https:\/\/www.alimentoslapedriza.com\/fr\/#\/schema\/person\/33591e0e18f812251967156e9f483659"},"headline":"Preocupa el exceso de peso de los menores","datePublished":"2015-11-12T10:00:27+00:00","dateModified":"2023-09-25T07:30:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/"},"wordCount":353,"commentCount":0,"publisher":{"@id":"https:\/\/www.alimentoslapedriza.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-content\/uploads\/sites\/12\/2015\/11\/obesidad_infantil.jpg","keywords":["exceso de peso","infantil","obesidad","obesidad infantil","OMS","peso"],"articleSection":["Blog","Ni\u00f1os","Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/","url":"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/","name":"Preocupa el exceso de peso de los menores - Alimentos La Pedriza","isPartOf":{"@id":"https:\/\/www.alimentoslapedriza.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/#primaryimage"},"image":{"@id":"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-content\/uploads\/sites\/12\/2015\/11\/obesidad_infantil.jpg","datePublished":"2015-11-12T10:00:27+00:00","dateModified":"2023-09-25T07:30:44+00:00","breadcrumb":{"@id":"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/#primaryimage","url":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-content\/uploads\/sites\/12\/2015\/11\/obesidad_infantil.jpg","contentUrl":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-content\/uploads\/sites\/12\/2015\/11\/obesidad_infantil.jpg","width":1240,"height":775},{"@type":"BreadcrumbList","@id":"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/preocupa-el-exceso-de-peso-de-los-menores\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.alimentoslapedriza.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Preocupa el exceso de peso de los menores"}]},{"@type":"WebSite","@id":"https:\/\/www.alimentoslapedriza.com\/fr\/#website","url":"https:\/\/www.alimentoslapedriza.com\/fr\/","name":"Alimentos La Pedriza","description":"Legumbres La Pedriza | Prenez votre temps","publisher":{"@id":"https:\/\/www.alimentoslapedriza.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alimentoslapedriza.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.alimentoslapedriza.com\/fr\/#organization","name":"Alimentos La Pedriza","url":"https:\/\/www.alimentoslapedriza.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alimentoslapedriza.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-content\/uploads\/sites\/12\/2023\/08\/Logo-casa-vertical-26.png","contentUrl":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-content\/uploads\/sites\/12\/2023\/08\/Logo-casa-vertical-26.png","width":512,"height":398,"caption":"Alimentos La Pedriza"},"image":{"@id":"https:\/\/www.alimentoslapedriza.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.alimentoslapedriza.com\/fr\/#\/schema\/person\/33591e0e18f812251967156e9f483659","name":"iBrenoc","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a933354c7a617a984d8fbf8e98e5511c48f16e03dd9bddfdec0ddefe88c3fada?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a933354c7a617a984d8fbf8e98e5511c48f16e03dd9bddfdec0ddefe88c3fada?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a933354c7a617a984d8fbf8e98e5511c48f16e03dd9bddfdec0ddefe88c3fada?s=96&d=mm&r=g","caption":"iBrenoc"},"sameAs":["https:\/\/www.alimentoslapedriza.com"],"url":"https:\/\/www.alimentoslapedriza.com\/fr\/blog\/author\/ibrenoc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-json\/wp\/v2\/posts\/859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-json\/wp\/v2\/comments?post=859"}],"version-history":[{"count":1,"href":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-json\/wp\/v2\/posts\/859\/revisions"}],"predecessor-version":[{"id":2037,"href":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-json\/wp\/v2\/posts\/859\/revisions\/2037"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-json\/wp\/v2\/media\/2036"}],"wp:attachment":[{"href":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-json\/wp\/v2\/media?parent=859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-json\/wp\/v2\/categories?post=859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alimentoslapedriza.com\/fr\/wp-json\/wp\/v2\/tags?post=859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}