{"id":884,"date":"2015-12-13T10:00:51","date_gmt":"2015-12-13T09:00:51","guid":{"rendered":"https:\/\/www.alimentoslapedriza.com\/?p=884"},"modified":"2023-09-21T12:38:35","modified_gmt":"2023-09-21T10:38:35","slug":"legumbres-y-salud","status":"publish","type":"post","link":"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/","title":{"rendered":"Legumbres y salud"},"content":{"rendered":"<p style=\"text-align: justify\">Sobra decir que las legumbres son muy beneficiosas para la salud pero, \u00bfcu\u00e1l es la raz\u00f3n de ello?<\/p>\n<p style=\"text-align: justify\">Adem\u00e1s de su composici\u00f3n nutricional que incluye gran cantidad de hidratos, prote\u00ednas, hierro y fibra, ayuda a prevenir enfermedades gastrointestinales como el c\u00e1ncer de colon, as\u00ed como combatir el estre\u00f1imiento y el colesterol malo, ya que por otro lado ayuda a la absorci\u00f3n del colesterol bueno, adem\u00e1s de controlar la tensi\u00f3n arterial y prevenir efectos cong\u00e9nitos.<\/p>\n<p style=\"text-align: justify\">Por otro lado y de cara a los excesos que nos procuran estas fechas, hemos de decir que las legumbres tienen gran capacidad saciante, es decir, nos llenan con una dosis justa y necesaria de alimento.<\/p>\n<p style=\"text-align: justify\">\u00bfA qu\u00e9 esperas para echarlas en remojo?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sobra decir que las legumbres son muy beneficiosas para la salud pero, \u00bfcu\u00e1l es la raz\u00f3n de ello? Adem\u00e1s de su composici\u00f3n nutricional que incluye gran cantidad de hidratos, prote\u00ednas, hierro y fibra, ayuda a prevenir enfermedades gastrointestinales como el c\u00e1ncer de colon, as\u00ed como combatir el estre\u00f1imiento y el colesterol malo, ya que por [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2031,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[30,46],"tags":[93,94,95,7,92],"class_list":["post-884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-salud","tag-aportes","tag-fibra","tag-hierro","tag-legumbres","tag-nutricion"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Legumbres y salud - Alimentos La Pedriza<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Legumbres y salud - Alimentos La Pedriza\" \/>\n<meta property=\"og:description\" content=\"Sobra decir que las legumbres son muy beneficiosas para la salud pero, \u00bfcu\u00e1l es la raz\u00f3n de ello? Adem\u00e1s de su composici\u00f3n nutricional que incluye gran cantidad de hidratos, prote\u00ednas, hierro y fibra, ayuda a prevenir enfermedades gastrointestinales como el c\u00e1ncer de colon, as\u00ed como combatir el estre\u00f1imiento y el colesterol malo, ya que por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/\" \/>\n<meta property=\"og:site_name\" content=\"Alimentos La Pedriza\" \/>\n<meta property=\"article:published_time\" content=\"2015-12-13T09:00:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-21T10:38:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.alimentoslapedriza.com\/en\/wp-content\/uploads\/sites\/11\/2015\/12\/legumbres_salud.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"iBrenoc\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"iBrenoc\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/blog\\\/legumbres-y-salud\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/blog\\\/legumbres-y-salud\\\/\"},\"author\":{\"name\":\"iBrenoc\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/#\\\/schema\\\/person\\\/33591e0e18f812251967156e9f483659\"},\"headline\":\"Legumbres y salud\",\"datePublished\":\"2015-12-13T09:00:51+00:00\",\"dateModified\":\"2023-09-21T10:38:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/blog\\\/legumbres-y-salud\\\/\"},\"wordCount\":131,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/blog\\\/legumbres-y-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2015\\\/12\\\/legumbres_salud.jpg\",\"keywords\":[\"aportes\",\"fibra\",\"hierro\",\"Legumbres\",\"nutrici\u00f3n\"],\"articleSection\":[\"Blog\",\"Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/blog\\\/legumbres-y-salud\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/blog\\\/legumbres-y-salud\\\/\",\"url\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/blog\\\/legumbres-y-salud\\\/\",\"name\":\"Legumbres y salud - Alimentos La Pedriza\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/blog\\\/legumbres-y-salud\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/blog\\\/legumbres-y-salud\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2015\\\/12\\\/legumbres_salud.jpg\",\"datePublished\":\"2015-12-13T09:00:51+00:00\",\"dateModified\":\"2023-09-21T10:38:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/blog\\\/legumbres-y-salud\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/blog\\\/legumbres-y-salud\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/blog\\\/legumbres-y-salud\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2015\\\/12\\\/legumbres_salud.jpg\",\"contentUrl\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2015\\\/12\\\/legumbres_salud.jpg\",\"width\":1000,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/blog\\\/legumbres-y-salud\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Legumbres y salud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/\",\"name\":\"Alimentos La Pedriza\",\"description\":\"Legumbres La Pedriza | Take your time\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/#organization\",\"name\":\"Alimentos La Pedriza\",\"url\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/08\\\/Logo-casa-vertical-26.png\",\"contentUrl\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2023\\\/08\\\/Logo-casa-vertical-26.png\",\"width\":512,\"height\":398,\"caption\":\"Alimentos La Pedriza\"},\"image\":{\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/#\\\/schema\\\/person\\\/33591e0e18f812251967156e9f483659\",\"name\":\"iBrenoc\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a933354c7a617a984d8fbf8e98e5511c48f16e03dd9bddfdec0ddefe88c3fada?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a933354c7a617a984d8fbf8e98e5511c48f16e03dd9bddfdec0ddefe88c3fada?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a933354c7a617a984d8fbf8e98e5511c48f16e03dd9bddfdec0ddefe88c3fada?s=96&d=mm&r=g\",\"caption\":\"iBrenoc\"},\"sameAs\":[\"https:\\\/\\\/www.alimentoslapedriza.com\"],\"url\":\"https:\\\/\\\/www.alimentoslapedriza.com\\\/en\\\/blog\\\/author\\\/ibrenoc\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Legumbres y salud - Alimentos La Pedriza","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/","og_locale":"es_ES","og_type":"article","og_title":"Legumbres y salud - Alimentos La Pedriza","og_description":"Sobra decir que las legumbres son muy beneficiosas para la salud pero, \u00bfcu\u00e1l es la raz\u00f3n de ello? Adem\u00e1s de su composici\u00f3n nutricional que incluye gran cantidad de hidratos, prote\u00ednas, hierro y fibra, ayuda a prevenir enfermedades gastrointestinales como el c\u00e1ncer de colon, as\u00ed como combatir el estre\u00f1imiento y el colesterol malo, ya que por [&hellip;]","og_url":"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/","og_site_name":"Alimentos La Pedriza","article_published_time":"2015-12-13T09:00:51+00:00","article_modified_time":"2023-09-21T10:38:35+00:00","og_image":[{"width":1000,"height":750,"url":"https:\/\/www.alimentoslapedriza.com\/en\/wp-content\/uploads\/sites\/11\/2015\/12\/legumbres_salud.jpg","type":"image\/jpeg"}],"author":"iBrenoc","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"iBrenoc","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/#article","isPartOf":{"@id":"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/"},"author":{"name":"iBrenoc","@id":"https:\/\/www.alimentoslapedriza.com\/en\/#\/schema\/person\/33591e0e18f812251967156e9f483659"},"headline":"Legumbres y salud","datePublished":"2015-12-13T09:00:51+00:00","dateModified":"2023-09-21T10:38:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/"},"wordCount":131,"commentCount":0,"publisher":{"@id":"https:\/\/www.alimentoslapedriza.com\/en\/#organization"},"image":{"@id":"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alimentoslapedriza.com\/en\/wp-content\/uploads\/sites\/11\/2015\/12\/legumbres_salud.jpg","keywords":["aportes","fibra","hierro","Legumbres","nutrici\u00f3n"],"articleSection":["Blog","Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/","url":"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/","name":"Legumbres y salud - Alimentos La Pedriza","isPartOf":{"@id":"https:\/\/www.alimentoslapedriza.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/#primaryimage"},"image":{"@id":"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/#primaryimage"},"thumbnailUrl":"https:\/\/www.alimentoslapedriza.com\/en\/wp-content\/uploads\/sites\/11\/2015\/12\/legumbres_salud.jpg","datePublished":"2015-12-13T09:00:51+00:00","dateModified":"2023-09-21T10:38:35+00:00","breadcrumb":{"@id":"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/#primaryimage","url":"https:\/\/www.alimentoslapedriza.com\/en\/wp-content\/uploads\/sites\/11\/2015\/12\/legumbres_salud.jpg","contentUrl":"https:\/\/www.alimentoslapedriza.com\/en\/wp-content\/uploads\/sites\/11\/2015\/12\/legumbres_salud.jpg","width":1000,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/www.alimentoslapedriza.com\/en\/blog\/legumbres-y-salud\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.alimentoslapedriza.com\/en\/"},{"@type":"ListItem","position":2,"name":"Legumbres y salud"}]},{"@type":"WebSite","@id":"https:\/\/www.alimentoslapedriza.com\/en\/#website","url":"https:\/\/www.alimentoslapedriza.com\/en\/","name":"Alimentos La Pedriza","description":"Legumbres La Pedriza | Take your time","publisher":{"@id":"https:\/\/www.alimentoslapedriza.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.alimentoslapedriza.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.alimentoslapedriza.com\/en\/#organization","name":"Alimentos La Pedriza","url":"https:\/\/www.alimentoslapedriza.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.alimentoslapedriza.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.alimentoslapedriza.com\/en\/wp-content\/uploads\/sites\/11\/2023\/08\/Logo-casa-vertical-26.png","contentUrl":"https:\/\/www.alimentoslapedriza.com\/en\/wp-content\/uploads\/sites\/11\/2023\/08\/Logo-casa-vertical-26.png","width":512,"height":398,"caption":"Alimentos La Pedriza"},"image":{"@id":"https:\/\/www.alimentoslapedriza.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.alimentoslapedriza.com\/en\/#\/schema\/person\/33591e0e18f812251967156e9f483659","name":"iBrenoc","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a933354c7a617a984d8fbf8e98e5511c48f16e03dd9bddfdec0ddefe88c3fada?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a933354c7a617a984d8fbf8e98e5511c48f16e03dd9bddfdec0ddefe88c3fada?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a933354c7a617a984d8fbf8e98e5511c48f16e03dd9bddfdec0ddefe88c3fada?s=96&d=mm&r=g","caption":"iBrenoc"},"sameAs":["https:\/\/www.alimentoslapedriza.com"],"url":"https:\/\/www.alimentoslapedriza.com\/en\/blog\/author\/ibrenoc\/"}]}},"_links":{"self":[{"href":"https:\/\/www.alimentoslapedriza.com\/en\/wp-json\/wp\/v2\/posts\/884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.alimentoslapedriza.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.alimentoslapedriza.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.alimentoslapedriza.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.alimentoslapedriza.com\/en\/wp-json\/wp\/v2\/comments?post=884"}],"version-history":[{"count":1,"href":"https:\/\/www.alimentoslapedriza.com\/en\/wp-json\/wp\/v2\/posts\/884\/revisions"}],"predecessor-version":[{"id":2032,"href":"https:\/\/www.alimentoslapedriza.com\/en\/wp-json\/wp\/v2\/posts\/884\/revisions\/2032"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.alimentoslapedriza.com\/en\/wp-json\/wp\/v2\/media\/2031"}],"wp:attachment":[{"href":"https:\/\/www.alimentoslapedriza.com\/en\/wp-json\/wp\/v2\/media?parent=884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.alimentoslapedriza.com\/en\/wp-json\/wp\/v2\/categories?post=884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.alimentoslapedriza.com\/en\/wp-json\/wp\/v2\/tags?post=884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}